{"id":3827,"date":"2023-03-31T18:55:19","date_gmt":"2023-03-31T16:55:19","guid":{"rendered":"https:\/\/therefore.net\/capabilities\/integration\/"},"modified":"2026-01-06T17:23:32","modified_gmt":"2026-01-06T16:23:32","slug":"integration","status":"publish","type":"capabilities","link":"https:\/\/therefore.net\/de\/funktionen\/integration\/","title":{"rendered":"Integration"},"content":{"rendered":"<section class=\"custom-block benefits-save-money\">\n    <div class=\"container benefits-save-money__container\">\n        <div class=\"benefits-save-money__inner\">\n\n            <div class=\"benefits-save-money__text-wrapper\">\n                <h2 class=\"benefits-save-money__title\">\n                    \n                <\/h2>\n                                    <div class=\"benefits-save-money__text\"><p>Die Integration von Drittanbietersystemen wie ERPs, CRMs und anderen Gesch\u00e4ftsanwendungen mit Therefore\u2122 kann Unternehmen, die ihre Abl\u00e4ufe optimieren und die Effizienz steigern m\u00f6chten, mehrere Vorteile bieten. Durch die Verbindung unterschiedlicher Systeme und Datenquellen erm\u00f6glicht die Integration die Automatisierung von Routineprozessen, wodurch die manuelle Dateneingabe und Fehler reduziert werden und die Mitarbeiter sich auf h\u00f6herwertige Aufgaben konzentrieren k\u00f6nnen. Dar\u00fcber hinaus kann die Integration einen zentralen \u00dcberblick \u00fcber die system\u00fcbergreifenden Informationen bieten, was eine schnellere und fundiertere Entscheidungsfindung erm\u00f6glicht. Auf diese Weise erhalten Unternehmen einen vollst\u00e4ndigeren und genaueren \u00dcberblick \u00fcber ihre Daten und k\u00f6nnen Muster und Trends erkennen, die in die Gesch\u00e4ftsstrategie einflie\u00dfen und das Wachstum f\u00f6rdern k\u00f6nnen.<\/p>\n<\/div>\n                \n            <\/div>\n\n            <div class=\"benefits-save-money__image-wrapper\">\n                                    <img decoding=\"async\" width=\"1410\" height=\"1060\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration.png\" class=\"attachment-full size-full\" alt=\"Eine Gruppe von Menschen in Gesch\u00e4ftskleidung steht im Kreis und legt ihre H\u00e4nde in der Mitte zusammen, um Teamwork und Einheit zu symbolisieren.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration.png 1410w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration-300x226.png 300w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration-1024x770.png 1024w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration-768x577.png 768w\" sizes=\"(max-width: 1410px) 100vw, 1410px\" \/>\n                                            <\/div>\n\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"custom-block view-pages-img-bullet view-pages-img-bullet--has-image\">\n    <div class=\"container view-pages-img-bullet__container\">\n        <div class=\"view-pages-img-bullet__inner\">\n                            <div class=\"view-pages-img-bullet__left\">\n                    <div class=\"view-pages-img-bullet__image-wrapper\">\n                        <img decoding=\"async\" width=\"1030\" height=\"1540\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration2.png\" class=\"attachment-full size-full\" alt=\"Ein Netz aus schwarzen Schn\u00fcren verbindet mehrere wei\u00dfe Stecknadeln auf einer wei\u00dfen Fl\u00e4che, wobei eine rosa Stecknadel und eine gelbe Stecknadel zwischen den wei\u00dfen Stecknadeln hervorstechen.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration2.png 1030w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration2-201x300.png 201w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration2-685x1024.png 685w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration2-768x1148.png 768w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Integration2-1027x1536.png 1027w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/>\n                    <\/div>\n                <\/div>\n            \n            <div class=\"view-pages-img-bullet__text-wrapper\">\n                                    <h2 class=\"view-pages-img-bullet__title\">\n                        Therefore\u2122 bietet zahlreiche Integrationsm\u00f6glichkeiten, darunter:\n                    <\/h2>\n                                                    <div class=\"view-pages-img-bullet__bullets-wrapper\">\n                        <ul class=\"view-pages-img-bullet__bullets\">\n                                                            \n                                <li class=\"view-pages-img-bullet__bullets__item\">\n                                    <h3 class=\"view-pages-img-bullet__bullets__item__title\">\n                                        Externe Konnektoren\n                                    <\/h3>\n                                    <div class=\"view-pages-img-bullet__bullets__item__text\"><p>Therefore\u2122 bietet vorgefertigte, systemeigene Konnektoren f\u00fcr eine Reihe beliebter Drittsysteme, darunter: <strong>SAP, Xero, <\/strong><strong>Microsoft <\/strong><strong>Dynamics 365 Business Central und NAV, Microsoft Share Point, Microsoft Office, Microsoft Power BI, PlanetPress, uniFLOW, I.R.I.S., sowie verschiedene Anbieter von EFSS- und eSignatur-Diensten.<br \/>\n<\/strong><\/p>\n<\/div>\n                                <\/li>\n                                                            \n                                <li class=\"view-pages-img-bullet__bullets__item\">\n                                    <h3 class=\"view-pages-img-bullet__bullets__item__title\">\n                                        Interne Konnektoren\n                                    <\/h3>\n                                    <div class=\"view-pages-img-bullet__bullets__item__text\"><p>Therefore\u2122 bietet eine Reihe n\u00fctzlicher interner Tools f\u00fcr die Integration auf andere intelligente Weise. Dazu geh\u00f6ren der <strong>Therefore\u2122 Content Connector<\/strong> und <strong>der Universal Connector<\/strong>.<\/p>\n<\/div>\n                                <\/li>\n                                                            \n                                <li class=\"view-pages-img-bullet__bullets__item\">\n                                    <h3 class=\"view-pages-img-bullet__bullets__item__title\">\n                                        Integration \u00fcber die API\n                                    <\/h3>\n                                    <div class=\"view-pages-img-bullet__bullets__item__text\"><p>Therefore\u2122 ist offen f\u00fcr die Integration. Es bietet nicht nur eine offene API f\u00fcr endlose Integrationsm\u00f6glichkeiten, sondern auch native Unterst\u00fctzung f\u00fcr REST-Aufrufe, sodass Therefore\u2122 problemlos in jede Branchenl\u00f6sung integriert werden kann, die eine REST-API bietet.<\/p>\n<\/div>\n                                <\/li>\n                                                    <\/ul>\n                    <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"custom-block join-therefore\">\n    <div class=\"container\">\n        <div class=\"join-therefore__inner\">\n                        <div class=\"join-therefore__title-wrapper\">\n                                <h6 class=\"join-therefore__title\">\n                    Externe Konnektoren\n                <\/h6>\n            <\/div>\n                        <div class=\"join-therefore__text-wrapper\">\n                <p class=\"join-therefore__text\">Therefore\u2122 macht es einfach, eine Verbindung zu einigen der beliebtesten Line-of-Business-L\u00f6sungen auf dem Markt herzustellen.<\/p>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--image\">\n                                            <img decoding=\"async\" width=\"635\" height=\"317\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignatures-Website.png\" class=\"attachment-full size-full\" alt=\"Logos von zehn elektronischen Signaturplattformen - Adobe Sign, DocuSign, HELLOSIGN, PleaseSign, Sinatura, Skribble, SimpleSign, yousign, scrive und circularo-zeigen die Integration mit Therefore\u2122.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignatures-Website.png 635w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignatures-Website-300x150.png 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Integration mit eSignatur-Anbietern<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page1R_mcid14\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\">In Therefore\u2122 gespeicherte Dokumente k\u00f6nnen mit einem unterst\u00fctzten eSignatur-Konto zum Signieren gesendet werden. Therefore\u2122 verf\u00fcgt \u00fcber standardm\u00e4\u00dfige Konnektoren f\u00fcr viele beliebte eSignatur-Anbieter, darunter DocuSign, HelloSign, AdobeSign und andere. Der gesamte Prozess der rechtlichen Unterzeichnung wird vom eSignatur-Anbieter abgewickelt. Nach Abschluss k\u00f6nnen die Dokumente manuell oder automatisch abgerufen und in Therefore\u2122 gespeichert werden. Dar\u00fcber hinaus erm\u00f6glicht eine herstellerneutrale API-Schnittstelle die einfache Herstellung zus\u00e4tzlicher Verbindungen zu anderen eSignatur-Anbietern.<\/span><\/span><\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--image\">\n                                            <img decoding=\"async\" width=\"635\" height=\"317\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Office.png\" class=\"attachment-full size-full\" alt=\"Ein Screenshot eines Word-Dokuments mit dem Titel &quot;Urlaubsantragsformular&quot; mit Feldern f\u00fcr Name, Datum, Abteilung und Urlaubsdaten. Das Moyaware-Logo erscheint oben links, und das Word-Men\u00fc ist oben sichtbar.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Office.png 635w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Office-300x150.png 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Integration mit Microsoft Office<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page138R_mcid2\" class=\"markedContent\"><\/span>Die Integration mit Microsoft Office ist bei allen Therefore\u2122-Versionen Standard. Speichern Sie Dokumente und E-Mails in Therefore\u2122 aus Office-Anwendungen wie Word, Excel, Outlook und anderen. Verwenden Sie Office-Vorlagen, um neue Therefore\u2122-Dokumente zu erstellen, oder generieren Sie neue Office-Dokumente mit Informationen aus Therefore\u2122.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape \">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Power-BI-in-Therefore.mp4\" name=\"power-bi-in-therefore\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Integration mit Microsoft Power BI<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page138R_mcid2\" class=\"markedContent\"><\/span>Die eingebaute Integration der Therefore\u2122-Software in Microsoft Power BI verbessert die Analysef\u00e4higkeiten von Therefore\u2122, indem sie ein interaktives Dashboard der Unternehmensdaten in Echtzeit bereitstellt, das einfach zu konfigurieren und zu nutzen ist. Die Benutzer k\u00f6nnen Berichte spontan anpassen und ihre Daten so strukturieren, wie es f\u00fcr sie sinnvoll ist. Manager k\u00f6nnen ihre Informationen aus einer einzigen Ansicht der Echtzeitdaten im Therefore\u2122-System optimal nutzen. Der mobile Zugriff \u00fcber die Power BI-App bedeutet, dass die Benutzer ihre Daten mitnehmen k\u00f6nnen und nie im Dunkeln stehen.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Therefore-Connector-for-Microsoft-Dynamics-Business-Central.mp4\" name=\"therefore-connector-fur-microsoft-dynamics-business-central\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Connector f\u00fcr Microsoft Dynamics 365 Business Central<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page129R_mcid0\" class=\"markedContent\"><\/span>Business Central ist die neueste Version der Microsoft Dynamics-Reihe von ERP\/CRM-L\u00f6sungen f\u00fcr kleine und mittlere Unternehmen. Diese neue Version, die fr\u00fcher Microsoft Dynamics NAV und Navision hie\u00df, ist Cloud-basiert und bietet L\u00f6sungen f\u00fcr die Verwaltung von Informationen \u00fcber Finanzen, Kunden, Vertrieb und Kundenservice.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape \">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/SharePointUser.mp4\" name=\"sharepointuser-2\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Connector f\u00fcr Microsoft SharePoint<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page138R_mcid2\" class=\"markedContent\"><\/span>Therefore\u2122 in Verbindung mit SharePoint\u00ae verbessert die Effizienz Ihres B\u00fcros. Durch die Integration von Therefore\u2122 mit SharePoint k\u00f6nnen einzelne Dokumente oder ganze Bibliotheken von SharePoint nach Therefore\u2122 verschoben werden. Einmal in Therefore\u2122, erweitern Workflow- und Scan-Tools Ihre SharePoint-Erfahrung.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/06\/Integrated-Accounts-Payable-solution-with-Xero.mp4\" name=\"integrated-accounts-payable-solution-with-xero-2\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Integration mit Xero<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p>Automatisieren Sie Ihre Kreditorenbuchhaltung durch eine 2-Wege-Integration mit Xero. Optimieren Sie die Prozesse der Kreditorenbuchhaltung und verbessern Sie die Produktivit\u00e4t durch Automatisierung.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/therefore.net\/integration-with-xero\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Klicken Sie hier, um mehr \u00fcber die Therefore\u2122-Integration mit Xero zu erfahren.<\/span><\/a><\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape \">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/SAP-and-Therefore.mp4\" name=\"sap-und-therefore\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Connector f\u00fcr SAP<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p>Der Therefore\u2122 Connector f\u00fcr SAP erm\u00f6glicht es, Daten zwischen den Systemen SAP und Therefore\u2122 zu senden. Der Connector basiert auf ArchiveLink und ist von SAP f\u00fcr die Integration mit S\/4HANA und NetWeaver zertifiziert. Durch die Verwendung des Therefore\u2122-Systems in Verbindung mit SAP ist es m\u00f6glich, die Nutzung beider Systeme zu maximieren, die Sichtbarkeit und Zug\u00e4nglichkeit von wichtigen Gesch\u00e4ftsdaten zu erh\u00f6hen und die langfristige Leistung Ihres SAP-Systems zu gew\u00e4hrleisten.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--image\">\n                                            <img decoding=\"async\" width=\"635\" height=\"317\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/uniflow-iris.png\" class=\"attachment-full size-full\" alt=\"Die Logos von uniFLOW und I.R.I.S., einem Canon Unternehmen, erscheinen auf wei\u00dfem Hintergrund. Das uniFLOW-Logo ist grau und rot mit quadratischen Grafiken, w\u00e4hrend das I.R.I.S.-Logo blau mit einem kreisf\u00f6rmigen Design und fetter Schrift ist.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/uniflow-iris.png 635w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/uniflow-iris-300x150.png 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Integration mit uniFLOW und I.R.I.S.<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p>Als Mitglied der Canon Software-Familie l\u00e4sst sich Therefore\u2122 sehr gut mit den Canon Output-Management-L\u00f6sungen uniFLOW und uniFLOW Online sowie den Dokumentenscan-L\u00f6sungen von I.R.I.S. integrieren.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape \">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--image\">\n                                            <img decoding=\"async\" width=\"635\" height=\"317\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/EFSS2.png\" class=\"attachment-full size-full\" alt=\"Logos von vier beliebten Cloud-Speicherdiensten: OneDrive (blaue Wolke), Dropbox (blaue offene Box), Box (blaue Wortmarke) und Google Drive (Dreieck mit gr\u00fcnen, gelben und blauen Abschnitten) auf wei\u00dfem Hintergrund.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/EFSS2.png 635w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/EFSS2-300x150.png 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Integration mit EFSS-Anbietern<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page1R_mcid14\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\">EFSS steht f\u00fcr Enterprise File Sync and Share und bezeichnet eine Reihe von Softwaretools und Diensten, die es Unternehmen erm\u00f6glichen, Dateien und Dokumente sicher zu speichern, zu synchronisieren und \u00fcber mehrere Ger\u00e4te und Benutzer hinweg gemeinsam zu nutzen. Therefore\u2122 ist mit den 4 wichtigsten Anbietern von Cloud-EFSS-Diensten integriert. Automatisches Importieren, Indizieren und Speichern von Dokumenten aus Microsoft OneDrive, Google Drive, Dropbox und Box mit dem Therefore\u2122 Content Connector. Geben Sie Dokumente automatisch \u00fcber Workflow-Funktionen frei.<\/span><\/span><\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n<section class=\"custom-block join-therefore\">\n    <div class=\"container\">\n        <div class=\"join-therefore__inner\">\n                        <div class=\"join-therefore__title-wrapper\">\n                                <h2 class=\"join-therefore__title\">\n                    Interne Konnektoren\n                <\/h2>\n            <\/div>\n                        <div class=\"join-therefore__text-wrapper\">\n                <p class=\"join-therefore__text\">Therefore\u2122 bietet eine Reihe n\u00fctzlicher interner Tools f\u00fcr die Integration auf andere clevere Weise.<\/p>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/The-Therefore-Content-Connector.mp4\" name=\"der-therefore-content-connector\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Content Connector<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page138R_mcid2\" class=\"markedContent\"><\/span><span id=\"page1R_mcid14\" class=\"markedContent\"><\/span><span id=\"page26R_mcid82\" class=\"markedContent\"><\/span>Der Therefore\u2122 Content Connector l\u00e4uft als Dienst, der Eingangsordner und Postf\u00e4cher \u00fcberwacht und Dokumente automatisch anhand definierter Indexierungsprofile verarbeitet. Er kann Dokumente aus Ordnern, Postf\u00e4chern und Cloud-EFSS-Plattformen importieren und indizieren. Er wird als \u00dcberwachungsdienst ausgef\u00fchrt, so dass nur eine Content Connector-Lizenz pro System und nicht pro Benutzer ben\u00f6tigt wird.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n<div class=\"custom-block simple-paragraph\">\n    <div class=\"container\">\n        <div class=\"blog-post__content blog-post__content--wide\">\n            <h2>Der Therefore\u2122 Content Connector kann:<\/h2>\n<ul>\n<li>Indexdaten aus dem Dateinamen oder dem Inhalt von Text-, PDF- und XML-Dateien extrahieren, um Dokumente automatisch in Therefore\u2122 zu speichern und zu indizieren. F\u00fcr TXT- und XML-Dateien k\u00f6nnen Sie ein Anzeigeformular definieren, das beim Anzeigen des Dokuments als Hintergrund verwendet wird.<span id=\"page26R_mcid91\" class=\"markedContent\"><br role=\"presentation\" \/><\/span><\/li>\n<li><span id=\"page26R_mcid92\" class=\"markedContent\"><\/span>Dokumente auf der Grundlage einer begleitenden TXT- oder XML-Datendatei automatisch speichern und indizieren (dies kann auch durch den Document Loader erfolgen).<\/li>\n<li>Mit eSignatur-Anbietern integriert werden und automatisch rechtsverbindliche Unterschriften von externen Parteien sammeln.<\/li>\n<li><span id=\"page26R_mcid99\" class=\"markedContent\">M<\/span><span id=\"page26R_mcid100\" class=\"markedContent\"><\/span>it Cloud-Speicherplattformen (Microsoft OneDrive, Google Drive, Box, Dropbox) integriert werden und Inhalte automatisch in Therefore\u2122 importieren.<\/li>\n<\/ul>\n\n        <\/div>\n\n            <\/div>\n<\/div>\n\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape \">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--image\">\n                                            <img decoding=\"async\" width=\"635\" height=\"317\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/UCicon.png\" class=\"attachment-full size-full\" alt=\"Ein lindgr\u00fcner Kreis mit einem dicken wei\u00dfen Ring und einem dunkelgrauen Zentrum. Zwei teilweise wei\u00dfe Ringe mit grauen Zentren erstrecken sich vom linken und rechten Rand und bilden ein symmetrisches abstraktes Muster.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/UCicon.png 635w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/UCicon-300x150.png 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 Universal Connector<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page138R_mcid2\" class=\"markedContent\"><\/span><span id=\"page1R_mcid14\" class=\"markedContent\"><\/span><span id=\"page26R_mcid82\" class=\"markedContent\"><\/span><span id=\"page436R_mcid1\" class=\"markedContent\"><\/span>Der Universal Connector bietet eine einfache, kodierungsfreie M\u00f6glichkeit zur Integration von Gesch\u00e4ftsanwendungen mit Therefore\u2122. Mit einem einfachen Tastendruck k\u00f6nnen Sie sofort verwandte Informationen aus Therefore\u2122 abrufen oder bereits indizierte Informationen in Ihrem Therefore\u2122-Repository speichern. Der Connector maximiert die Produktivit\u00e4t und schafft eine engere Verbindung zwischen den Informationen und Anwendungen, die in Ihrem Unternehmen routinem\u00e4\u00dfig verwendet werden.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n<div class=\"custom-block simple-paragraph\">\n    <div class=\"container\">\n        <div class=\"blog-post__content blog-post__content--wide\">\n            <h3><strong><span id=\"page1R_mcid31\" class=\"markedContent\"><\/span>Mit dem Universal Connector k\u00f6nnen Sie Informationen aus Anwendungen von Drittanbietern effizient mit Therefore\u2122 verbinden, indem Sie zwei Funktionalit\u00e4ten nutzen:<br \/>\n<\/strong><\/h3>\n<p><span id=\"page1R_mcid33\" class=\"markedContent\"><\/span><span id=\"page1R_mcid33\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\">\u2022<\/span><\/span><span id=\"page1R_mcid34\" class=\"markedContent\"> <\/span><span id=\"page1R_mcid39\" class=\"markedContent\">Die Zwischenablagefunktion verwendet jeden markierten Text aus praktisch jeder Anwendung, um Funktionen in Therefore\u2122 auszuf\u00fchren.<br role=\"presentation\" \/><span dir=\"ltr\" role=\"presentation\">\u2022<\/span><\/span><span id=\"page1R_mcid40\" class=\"markedContent\"> <\/span><span id=\"page1R_mcid45\" class=\"markedContent\">Die Scanfunktion durchsucht Dialoge in Anwendungen von Drittanbietern nach Metadaten und verwendet diese Informationen zum Speichern oder Suchen von Dokumenten.<\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-3936 aligncenter\" src=\"https:\/\/therefore.net\/app\/uploads\/2023\/03\/UC.png\" alt=\"\" width=\"730\" height=\"446\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/UC.png 730w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/UC-300x183.png 300w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/p>\n\n        <\/div>\n\n            <\/div>\n<\/div>\n\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--image\">\n                                            <img decoding=\"async\" width=\"635\" height=\"317\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/TableReplication.png\" class=\"attachment-full size-full\" alt=\"Links \u00fcberlagern sich zwei Tabellenkalkulationssymbole, davor zwei gr\u00fcne Pfeile, die in entgegengesetzte Richtungen zeigen. Auf der rechten Seite befindet sich das Therefore-Logo mit dem Text &quot;People Process Information&quot; darunter.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/TableReplication.png 635w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/TableReplication-300x150.png 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Externe Datenbanktabellen<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page138R_mcid2\" class=\"markedContent\"><\/span><span id=\"page1R_mcid14\" class=\"markedContent\"><\/span><span id=\"page26R_mcid82\" class=\"markedContent\"><\/span><span id=\"page436R_mcid1\" class=\"markedContent\"><span dir=\"ltr\" role=\"presentation\">Therefore\u2122 bietet Ihnen mehrere Optionen f\u00fcr die Integration mit externen Datenbanken. Ein g\u00e4ngiges Beispiel hierf\u00fcr ist die M\u00f6glichkeit, eine Tabelle mit Lieferanten oder Kunden zu verwenden, die in der Datenbank eines anderen Systems gespeichert ist. Sie k\u00f6nnen externe Tabellen mit Therefore\u2122 verbinden und dabei mehrere Optionen f\u00fcr die Synchronisierung der Daten w\u00e4hlen. Sogar Therefore\u2122 Online-Kunden k\u00f6nnen mit einer Methode namens Tabellenreplikation in eine externe Datenbank integriert werden. Diese Integration ist mit jeder Therefore\u2122-Edition ohne zus\u00e4tzliche Kosten m\u00f6glich.<\/span><\/span><\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n\n<p><\/p>\n\n\n<section class=\"custom-block join-therefore\">\n    <div class=\"container\">\n        <div class=\"join-therefore__inner\">\n                        <div class=\"join-therefore__title-wrapper\">\n                                <h2 class=\"join-therefore__title\">\n                    Ma\u00dfgeschneiderte L\u00f6sungen\n                <\/h2>\n            <\/div>\n                        <div class=\"join-therefore__text-wrapper\">\n                <p class=\"join-therefore__text\">Therefore\u2122 ist offen f\u00fcr die Integration. Die Therefore\u2122-API und die native Unterst\u00fctzung f\u00fcr REST-Aufrufe erm\u00f6glichen die Verbindung mit praktisch jedem System.<\/p>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--image\">\n                                            <img decoding=\"async\" width=\"635\" height=\"317\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/API.png\" class=\"attachment-full size-full\" alt=\"Blaue digitale Schnittstelle mit sechseckigen Symbolen, die mit Technologie zu tun haben, wie z. B. Zahnr\u00e4der, eine Gl\u00fchbirne, ein Schild und eine Gruppe von Menschen, wobei &quot;API&quot; in der Mitte hervorgehoben ist.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/API.png 635w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/API-300x150.png 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Therefore\u2122 API<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page138R_mcid2\" class=\"markedContent\"><\/span><span id=\"page1R_mcid14\" class=\"markedContent\"><\/span><span id=\"page26R_mcid82\" class=\"markedContent\"><\/span><span id=\"page436R_mcid1\" class=\"markedContent\"><\/span><span id=\"page151R_mcid1\" class=\"markedContent\"><\/span>Die Therefore\u2122 Application Program Interface (API) erm\u00f6glicht die einfache Integration mit Anwendungen wie ERP- oder CRM-Systemen und die Erstellung von anpassbaren, eigenst\u00e4ndigen Programmen, die mit dem Therefore\u2122-System arbeiten. Sie bietet die M\u00f6glichkeit, Informationen direkt aus einer Anwendung eines Drittanbieters nahtlos zu verkn\u00fcpfen und Ihre Arbeitsweise zu verbessern, indem Sie die ben\u00f6tigten Informationen leicht zug\u00e4nglich, sichtbar und sicher machen.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n<div class=\"custom-block simple-paragraph\">\n    <div class=\"container\">\n        <div class=\"blog-post__content blog-post__content--wide\">\n            <h3><strong><span id=\"page1R_mcid31\" class=\"markedContent\"><\/span>Die Therefore\u2122 API erm\u00f6glicht:<br \/>\n<\/strong><\/h3>\n<ul>\n<li><span id=\"page1R_mcid33\" class=\"markedContent\"><\/span>Integration mit Systemen von Drittanbietern.<\/li>\n<li>Suche nach Dokumenten, die in Therefore\u2122 gespeichert sind, aus Anwendungen von Drittanbietern heraus.<\/li>\n<li>Scannen und Erfassen von Dokumenten in Therefore\u2122 aus Anwendungen von Drittanbietern heraus.<\/li>\n<li>Bearbeiten und Anzeigen von in Therefore\u2122 gespeicherten Dokumenten in Anwendungen von Drittanbietern.<\/li>\n<li>Integration von Therefore\u2122 Workflow in Anwendungen von Drittanbietern.<\/li>\n<li>Sichere Speicherung von Dokumenten in Therefore\u2122 f\u00fcr ein verbessertes Datenmanagement in Anwendungen von Drittanbietern.<\/li>\n<\/ul>\n\n        <\/div>\n\n            <\/div>\n<\/div>\n\n\n\n\n<section class=\"custom-block video-img-section video-img-section--shape \">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--image\">\n                                            <img decoding=\"async\" width=\"635\" height=\"317\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/635x317-TF.png\" class=\"attachment-full size-full\" alt=\"Das Therefore-Logo mit den Worten &quot;PEOPLE PROCESS INFORMATION&quot; darunter. Die Buchstaben &quot;o&quot; in &quot;Therefore&quot; und zwei Punkte darunter sind gr\u00fcn hervorgehoben.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/635x317-TF.png 635w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/635x317-TF-300x150.png 300w\" sizes=\"(max-width: 635px) 100vw, 635px\" \/>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">REST-Aufrufe<\/h2>\n                \n                                    <div class=\"video-img-section__text\"><p><span id=\"page138R_mcid2\" class=\"markedContent\"><\/span><span id=\"page1R_mcid14\" class=\"markedContent\"><\/span><span id=\"page26R_mcid82\" class=\"markedContent\"><\/span><span id=\"page436R_mcid1\" class=\"markedContent\"><\/span><span id=\"page151R_mcid1\" class=\"markedContent\"><\/span>Therefore\u2122 unterst\u00fctzt Integrationsszenarien mit REST-Aufrufen. Therefore\u2122 kann einen REST-Aufruf aus einem Workflow heraus initiieren, um Informationen von einem externen Dienst oder einer externen Anwendung zu GET, POST, PUT, PATCH und DELETE in oder aus Therefore\u2122 zu \u00fcbertragen. Typische Anwendungsszenarien sind das Abrufen von Daten aus einem ERP-System und das Senden dieser Daten an Therefore\u2122, die Integration mit externen Websites wie W\u00e4hrungskonversation, Sprach\u00fcbersetzung oder das Senden von SMS \u00fcber die Integration mit einem SMS-Anbieterdienst. Praktisch jede App oder Software mit einer REST-API kann auf diese Weise integriert werden.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n\n\n<section class=\"custom-block hero-slider\">\n    <div class=\"hero-slider swiper-container\" data-timer=\"\">\n        <div class=\"swiper-wrapper swiper-wrapper--p-t\">\n                                                        <div class=\"swiper-slide\" data-swiper-autoplay=\"\">\n                    <div class=\"container hero-slider__container\">\n                        <div class=\"hero-slider__slide\">\n                            <div class=\"hero-slider__slide-left\">\n                                <h2 class=\"hero-slider__title\">\n                                    REST-Aufrufe in Therefore\u2122\n                                <\/h2>\n                                <p class=\"hero-slider__text text-light\">\n                                    Dieses Webinar ist eine nicht-technische Einf\u00fchrung in REST-Aufrufe in Therefore\u2122 auf hohem Niveau. Ziel ist es, Pre-Sales-Mitarbeitern und anderen Personen in \u00e4hnlichen Positionen ein konzeptionelles Verst\u00e4ndnis f\u00fcr diese Funktion zu vermitteln und sie in die Lage zu versetzen, L\u00f6sungen f\u00fcr Kundenprobleme zu finden. \n                                <\/p>\n                                                                <a class=\"main-button main-button--with-arrow\" target=\"_blank\"\n                                    href=\"https:\/\/www.youtube.com\/watch?v=LqpL6Xn-rFo\">Webinar ansehen (Englisch)<\/a>\n                                                            <\/div>\n                                                            <div class=\"hero-slider__slide-right\">\n                                                                            <img fetchpriority=\"high\" decoding=\"async\" width=\"910\" height=\"684\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/05\/RESTCalls2023Webinar.png\" class=\"attachment-1283x684 size-1283x684\" alt=\"Werbegrafik f\u00fcr das Webinar mit dem Titel &quot;REST-Aufrufe mit Therefore\u2122&quot; mit Logos und Fotos von Cono Fusco, Head of Digital Engagement, und Roman Djukic, Learning Manager.\" loading=\"eager\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/05\/RESTCalls2023Webinar.png 1410w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/05\/RESTCalls2023Webinar-300x226.png 300w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/05\/RESTCalls2023Webinar-1024x770.png 1024w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/05\/RESTCalls2023Webinar-768x577.png 768w\" sizes=\"(max-width: 910px) 100vw, 910px\" \/>\n                                                                    <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                            <div class=\"swiper-slide\" data-swiper-autoplay=\"\">\n                    <div class=\"container hero-slider__container\">\n                        <div class=\"hero-slider__slide\">\n                            <div class=\"hero-slider__slide-left\">\n                                <h2 class=\"hero-slider__title\">\n                                    Mehr \u00fcber Therefore\u2122 und Business Central\n                                <\/h2>\n                                <p class=\"hero-slider__text text-light\">\n                                    In diesem Video stellt Wolfgang Gogg von der Therefore Corporation den Therefore\u2122 Connector f\u00fcr Microsoft Dynamics 365 Business Central vor und geht auf die Installation, Konfiguration und eine Demo der Funktionen ein.\n                                <\/p>\n                                                                <a class=\"main-button main-button--with-arrow\" target=\"_blank\"\n                                    href=\"https:\/\/www.youtube.com\/watch?v=ZgyU7h07-O0\">Video ansehen (Englisch)<\/a>\n                                                            <\/div>\n                                                            <div class=\"hero-slider__slide-right\">\n                                                                            <img decoding=\"async\" width=\"910\" height=\"684\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/BCVideo.png\" class=\"attachment-1283x684 size-1283x684\" alt=\"Folie mit dem Titel &quot;Therefore Videos&quot;, die eine Demo f\u00fcr den Therefore Connector f\u00fcr Microsoft Dynamics 365 Business Central zeigt, mit einem Software Reviews Top Rated Abzeichen und Wolfgang Goggi, VP of Product, aufgef\u00fchrt.\" loading=\"lazy\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/BCVideo.png 1410w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/BCVideo-300x226.png 300w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/BCVideo-1024x770.png 1024w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/BCVideo-768x577.png 768w\" sizes=\"auto, (max-width: 910px) 100vw, 910px\" \/>\n                                                                    <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                <\/div>\n        <div class=\"swiper-pagination\"><\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>In der Welt von Big Data hilft Ihnen die Integration, die L\u00fccke zu schlie\u00dfen.<\/p>\n","protected":false},"template":"","class_list":["post-3827","capabilities","type-capabilities","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Integration mit Therefore\u2122<\/title>\n<meta name=\"description\" content=\"Die Integration von Therefore\u2122 in Drittsysteme wie ERPs, CRMs und andere Gesch\u00e4ftsanwendungen bietet Ihnen das Beste aus beiden Welten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/therefore.net\/de\/funktionen\/integration\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/funktionen\\\/integration\\\/\",\"url\":\"https:\\\/\\\/therefore.net\\\/de\\\/funktionen\\\/integration\\\/\",\"name\":\"Integration mit Therefore\u2122\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/#website\"},\"datePublished\":\"2023-03-31T16:55:19+00:00\",\"dateModified\":\"2026-01-06T16:23:32+00:00\",\"description\":\"Die Integration von Therefore\u2122 in Drittsysteme wie ERPs, CRMs und andere Gesch\u00e4ftsanwendungen bietet Ihnen das Beste aus beiden Welten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/funktionen\\\/integration\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/therefore.net\\\/de\\\/funktionen\\\/integration\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/funktionen\\\/integration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/therefore.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/therefore.net\\\/de\\\/\",\"name\":\"Therefore\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/therefore.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/#organization\",\"name\":\"Therefore\",\"url\":\"https:\\\/\\\/therefore.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/therefore.net\\\/wp\\\/..\\\/app\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/therefore.net\\\/wp\\\/..\\\/app\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"width\":176,\"height\":48,\"caption\":\"Therefore\"},\"image\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/therefore-corporation\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ThereforeTV\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Integration mit Therefore\u2122","description":"Die Integration von Therefore\u2122 in Drittsysteme wie ERPs, CRMs und andere Gesch\u00e4ftsanwendungen bietet Ihnen das Beste aus beiden Welten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/therefore.net\/de\/funktionen\/integration\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/therefore.net\/de\/funktionen\/integration\/","url":"https:\/\/therefore.net\/de\/funktionen\/integration\/","name":"Integration mit Therefore\u2122","isPartOf":{"@id":"https:\/\/therefore.net\/de\/#website"},"datePublished":"2023-03-31T16:55:19+00:00","dateModified":"2026-01-06T16:23:32+00:00","description":"Die Integration von Therefore\u2122 in Drittsysteme wie ERPs, CRMs und andere Gesch\u00e4ftsanwendungen bietet Ihnen das Beste aus beiden Welten.","breadcrumb":{"@id":"https:\/\/therefore.net\/de\/funktionen\/integration\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/therefore.net\/de\/funktionen\/integration\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/therefore.net\/de\/funktionen\/integration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/therefore.net\/de\/"},{"@type":"ListItem","position":2,"name":"Integration"}]},{"@type":"WebSite","@id":"https:\/\/therefore.net\/de\/#website","url":"https:\/\/therefore.net\/de\/","name":"Therefore","description":"","publisher":{"@id":"https:\/\/therefore.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/therefore.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/therefore.net\/de\/#organization","name":"Therefore","url":"https:\/\/therefore.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/therefore.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2022\/04\/logo.png","contentUrl":"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2022\/04\/logo.png","width":176,"height":48,"caption":"Therefore"},"image":{"@id":"https:\/\/therefore.net\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/therefore-corporation\/","https:\/\/www.youtube.com\/user\/ThereforeTV"]}]}},"_links":{"self":[{"href":"https:\/\/therefore.net\/de\/wp-json\/wp\/v2\/capabilities\/3827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/therefore.net\/de\/wp-json\/wp\/v2\/capabilities"}],"about":[{"href":"https:\/\/therefore.net\/de\/wp-json\/wp\/v2\/types\/capabilities"}],"wp:attachment":[{"href":"https:\/\/therefore.net\/de\/wp-json\/wp\/v2\/media?parent=3827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}