{"id":9232,"date":"2023-03-29T02:42:27","date_gmt":"2023-03-29T00:42:27","guid":{"rendered":"https:\/\/therefore.net\/capabilities\/firmas-electronicas\/"},"modified":"2025-03-05T17:44:50","modified_gmt":"2025-03-05T16:44:50","slug":"firmas-electronicas","status":"publish","type":"capabilities","link":"https:\/\/therefore.net\/es\/capabilities\/firmas-electronicas\/","title":{"rendered":"Firmas electr\u00f3nicas"},"content":{"rendered":"<section class=\"custom-block benefits-save-money\">\n    <div class=\"container benefits-save-money__container\">\n        <div class=\"benefits-save-money__inner\">\n\n            <div class=\"benefits-save-money__text-wrapper\">\n                <h2 class=\"benefits-save-money__title\">\n                    \n                <\/h2>\n                                    <div class=\"benefits-save-money__text\"><p>Therefore\u2122 puede integrarse con varios servicios de firma electr\u00f3nica de terceros, como HelloSign, DocuSign y AdobeSign, entre otros. Al digitalizar el proceso de firma, los proveedores de firma electr\u00f3nica eliminan la necesidad de imprimir, enviar y recuperar engorrosos documentos firmados. Los documentos guardados en Therefore\u2122 se pueden enviar para su firma mediante una cuenta de proveedor de firma electr\u00f3nica, ya sea manualmente desde Therefore\u2122 Viewer o autom\u00e1ticamente durante un proceso de flujo de trabajo. A continuaci\u00f3n, el proveedor de firma electr\u00f3nica se encarga de todo el proceso de firma legal. Una vez completado, los documentos pueden recuperarse manual o autom\u00e1ticamente y guardarse de nuevo en Therefore\u2122.<\/p>\n<\/div>\n                \n            <\/div>\n\n            <div class=\"benefits-save-money__image-wrapper\">\n                                    <img decoding=\"async\" width=\"1410\" height=\"1060\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature.png\" class=\"attachment-full size-full\" alt=\"Primer plano de dos personas utilizando una tableta; una de ellas da golpecitos en la pantalla, mientras que la otra sostiene un bol\u00edgrafo y se\u00f1ala la tableta; ambas llevan ropa de color claro.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature.png 1410w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-300x226.png 300w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-1024x770.png 1024w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-768x577.png 768w\" sizes=\"(max-width: 1410px) 100vw, 1410px\" \/>\n                                            <\/div>\n\n        <\/div>\n    <\/div>\n<\/section>\n<section class=\"custom-block bullet-shape \">\n    <div class=\"container bullet-shape__container\">\n                        <h1 class=\"bullet-shape__title\">C\u00f3mo funciona<\/h1>\n        <div class=\"bullet-shape__row\">\n                    <ul class=\"bullet-shape__items bullet-shape__items--left\">\n                                    <li><p><strong>PROCESAMIENTO MANUAL<br \/>\n<\/strong><\/p>\n<\/li>\n                                    <li><p>Obtener un documento firmado desde el Therefore\u2122 Viewer.<\/p>\n<\/li>\n                                    <li><p>Cargue el documento en el proveedor de firma electr\u00f3nica y seleccione los destinatarios, as\u00ed como la informaci\u00f3n necesaria de cada firmante.<\/p>\n<\/li>\n                                    <li><p>Los firmantes reciben un correo electr\u00f3nico del proveedor de firma electr\u00f3nica y pueden firmar f\u00e1cilmente los documentos. A continuaci\u00f3n, estos pueden guardarse e indexarse en Therefore mediante un perfil de indexaci\u00f3n para un procesamiento r\u00e1pido.<\/p>\n<\/li>\n                            <\/ul>\n        \n                    <ul class=\"bullet-shape__items bullet-shape__items--right\">\n                                    <li><p><strong>PROCESAMIENTO AUTOM\u00c1TICO<br \/>\n<\/strong><\/p>\n<\/li>\n                                    <li><p>Env\u00ede autom\u00e1ticamente un documento para su firma y gu\u00e1rdelo de nuevo en Therefore\u2122, sin interacci\u00f3n del usuario.<\/p>\n<\/li>\n                                    <li><p>Guarde un documento en Therefore\u2122 para iniciar el flujo de trabajo. El documento se env\u00eda para su firma seg\u00fan la plantilla de firma preconfigurada.<\/p>\n<\/li>\n                                    <li><p>Una vez firmados, Therefore\u2122 Content Connector descargar\u00e1 todos los documentos firmados y completados del proveedor de firma electr\u00f3nica. A continuaci\u00f3n, se guardan de nuevo en Therefore\u2122 sin ninguna interacci\u00f3n del usuario.<\/p>\n<\/li>\n                            <\/ul>\n            <\/div>\n    <\/div>\n<\/section>\n<section class=\"custom-block benefits-save-time\">\n    <div class=\"container benefits-save-time__container\">\n        <div class=\"benefits-save-time__inner\">\n            <div class=\"benefits-save-time__left\">\n                <div class=\"benefits-save-time__image-wrapper\">\n                                            <img decoding=\"async\" width=\"1030\" height=\"1120\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Together.png\" class=\"attachment-full size-full\" alt=\"A woman with long red hair in a plaid shirt and a man in a striped shirt discuss Therefore\u2122 Workflow, smiling at each other while seated in office chairs. A coffee cup rests on the desk in the foreground.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Together.png 1030w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Together-276x300.png 276w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Together-942x1024.png 942w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Together-768x835.png 768w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"benefits-save-time__text-wrapper\">\n                <h2 class=\"benefits-save-time__title\">\n                    Al utilizar la firma electr\u00f3nica con Therefore\u2122, empresas de todos los tama\u00f1os pueden obtener m\u00faltiples ventajas.\n                <\/h2>\n                                <ul class=\"benefits-save-time__bullets\">\n                                        <li class=\"benefits-save-time__bullets__item\">Recopile firmas jur\u00eddicamente vinculantes de forma r\u00e1pida y fiable, reduciendo costes y ahorrando tiempo.<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Aumente la productividad de los empleados eliminando los obst\u00e1culos inherentes a los procesos manuales de aprobaci\u00f3n y firma.<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Acelere los tiempos de transacci\u00f3n por documento para obtener mejores indicadores clave de rendimiento (KPI), como ciclos de venta m\u00e1s cortos y mayores tasas de conversi\u00f3n.<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Aumente la satisfacci\u00f3n de sus clientes facilit\u00e1ndoles la firma de documentos.<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Aseg\u00farese de que sus documentos est\u00e1n protegidos contra cambios no autorizados tanto antes como despu\u00e9s de firmarlos.<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Reduzca el impacto medioambiental causado por los documentos en papel digitalizando todo el proceso de firma.<\/li>\n                                    <\/ul>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"custom-block video-img-section  \">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/EN-Do-Less-Get-More-eSignatures.mp4\" name=\"en-do-less-get-more-esignatures-3\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">Haga menos, consiga m\u00e1s con las firmas electr\u00f3nicas en Therefore\u2122.<\/h2>\n                \n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n<section class=\"custom-block benefits-left-image \">\n    <div class=\"container  benefits-left-image__container\">\n        <div class=\"benefits-left-image__inner\">\n            <div class=\"benefits-left-image__image-wrapper benefits-left-image__image-wrapper--original\">\n                                    <img decoding=\"async\" width=\"1220\" height=\"1630\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-Legal.png\" class=\"attachment-full size-full\" alt=\"Un mazo de juez y una balanza descansan sobre dos libros de leyes abiertos, s\u00edmbolo de la justicia y los procedimientos judiciales, sobre un fondo blanco.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-Legal.png 1220w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-Legal-225x300.png 225w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-Legal-766x1024.png 766w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-Legal-768x1026.png 768w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/eSignature-Legal-1150x1536.png 1150w\" sizes=\"(max-width: 1220px) 100vw, 1220px\" \/>\n                            <\/div>\n            <div class=\"benefits-left-image__text-wrapper\">\n                                \n                    <div class=\"benefits-left-image__paragraph-wrapper\">\n                                                <h2 class=\"benefits-left-image__title\">\n                            Sobre la legalidad de la firma electr\u00f3nica frente a la firma f\u00edsica\n                        <\/h2>\n                        <div class=\"benefits-left-image__text\"><p>A medida que el mundo se vuelve cada vez m\u00e1s digital, las firmas electr\u00f3nicas, o eSignatures, se han vuelto m\u00e1s frecuentes en muchas industrias. La legalidad de las firmas electr\u00f3nicas var\u00eda en funci\u00f3n del pa\u00eds y la jurisdicci\u00f3n, pero en general se reconoce que son legalmente vinculantes en muchas partes del mundo.<\/p>\n<p>Por favor, tenga en cuenta que lo que sigue es s\u00f3lo para fines informativos generales y no debe interpretarse como asesoramiento jur\u00eddico. Le recomendamos encarecidamente que consulte con un experto cualificado de su elecci\u00f3n para comprender plenamente c\u00f3mo afecta a su organizaci\u00f3n el estatus legal de las firmas electr\u00f3nicas en su jurisdicci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfCu\u00e1l es la situaci\u00f3n legal de la firma electr\u00f3nica en Estados Unidos?<\/strong><\/p>\n<p>En Estados Unidos, la legalidad de las firmas electr\u00f3nicas se establece en la Ley de Firmas Electr\u00f3nicas en el Comercio Global y Nacional (ESIGN) y en la Ley Uniforme de Transacciones Electr\u00f3nicas (UETA). Estas leyes establecen el reconocimiento legal de las firmas electr\u00f3nicas y permiten su uso tanto en transacciones comerciales como gubernamentales. En virtud de estas leyes, las firmas electr\u00f3nicas se consideran jur\u00eddicamente vinculantes siempre que cumplan determinados requisitos, como ser identificables de forma \u00fanica, verificables y capaces de asociar de forma fiable la firma con el registro que se est\u00e1 firmando.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfCu\u00e1l es la situaci\u00f3n jur\u00eddica de la firma electr\u00f3nica en la Uni\u00f3n Europea?<\/strong><\/p>\n<p>En la Uni\u00f3n Europea, la firma electr\u00f3nica se rige por el Reglamento eIDAS, que establece un marco jur\u00eddico para la identificaci\u00f3n electr\u00f3nica y los servicios de confianza. Este reglamento establece tres niveles de firma electr\u00f3nica, el m\u00e1s alto de los cuales exige firmas electr\u00f3nicas avanzadas que cumplan estrictos requisitos de seguridad y autenticaci\u00f3n. Al igual que Estados Unidos, la UE reconoce la validez jur\u00eddica de las firmas electr\u00f3nicas, siempre que cumplan determinados requisitos y est\u00e9n debidamente autenticadas.<\/p>\n<p>Aunque el estatus legal de las firmas electr\u00f3nicas var\u00eda seg\u00fan el pa\u00eds y la jurisdicci\u00f3n, en general se consideran legalmente vinculantes en muchas partes del mundo. Con el creciente uso de las transacciones digitales, es probable que las firmas electr\u00f3nicas sean a\u00fan m\u00e1s frecuentes en los pr\u00f3ximos a\u00f1os. Sin embargo, es importante que las empresas conozcan los requisitos legales para la firma electr\u00f3nica en sus respectivas jurisdicciones y que busquen siempre el asesoramiento de un abogado cualificado para asegurarse de que sus transacciones electr\u00f3nicas son v\u00e1lidas y legalmente vinculantes.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n                    <\/div>\n\n                \n                    <div class=\"benefits-left-image__paragraph-wrapper\">\n                                                <h2 class=\"benefits-left-image__title\">\n                            \n                        <\/h2>\n                        <div class=\"benefits-left-image__text\"><\/div>\n                    <\/div>\n\n                                \n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Las firmas electr\u00f3nicas pueden simplificar y agilizar los procesos de firma de documentos, al tiempo que aumentan la seguridad y reducen el gasto de papel.<\/p>\n","protected":false},"template":"","class_list":["post-9232","capabilities","type-capabilities","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Firmas electr\u00f3nicas en Therefore\u2122<\/title>\n<meta name=\"description\" content=\"Las integraciones de Therefore\u2122 eSignatures est\u00e1n disponibles con una serie de servicios de firma electr\u00f3nica de terceros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/therefore.net\/es\/capabilities\/firmas-electronicas\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/capabilities\\\/firmas-electronicas\\\/\",\"url\":\"https:\\\/\\\/therefore.net\\\/es\\\/capabilities\\\/firmas-electronicas\\\/\",\"name\":\"Firmas electr\u00f3nicas en Therefore\u2122\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/#website\"},\"datePublished\":\"2023-03-29T00:42:27+00:00\",\"dateModified\":\"2025-03-05T16:44:50+00:00\",\"description\":\"Las integraciones de Therefore\u2122 eSignatures est\u00e1n disponibles con una serie de servicios de firma electr\u00f3nica de terceros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/capabilities\\\/firmas-electronicas\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/therefore.net\\\/es\\\/capabilities\\\/firmas-electronicas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/capabilities\\\/firmas-electronicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/therefore.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Firmas electr\u00f3nicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/therefore.net\\\/es\\\/\",\"name\":\"Therefore\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/therefore.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/#organization\",\"name\":\"Therefore\",\"url\":\"https:\\\/\\\/therefore.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/therefore.net\\\/wp\\\/..\\\/app\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/therefore.net\\\/wp\\\/..\\\/app\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"width\":176,\"height\":48,\"caption\":\"Therefore\"},\"image\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/therefore-corporation\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ThereforeTV\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Firmas electr\u00f3nicas en Therefore\u2122","description":"Las integraciones de Therefore\u2122 eSignatures est\u00e1n disponibles con una serie de servicios de firma electr\u00f3nica de terceros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/therefore.net\/es\/capabilities\/firmas-electronicas\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/therefore.net\/es\/capabilities\/firmas-electronicas\/","url":"https:\/\/therefore.net\/es\/capabilities\/firmas-electronicas\/","name":"Firmas electr\u00f3nicas en Therefore\u2122","isPartOf":{"@id":"https:\/\/therefore.net\/es\/#website"},"datePublished":"2023-03-29T00:42:27+00:00","dateModified":"2025-03-05T16:44:50+00:00","description":"Las integraciones de Therefore\u2122 eSignatures est\u00e1n disponibles con una serie de servicios de firma electr\u00f3nica de terceros.","breadcrumb":{"@id":"https:\/\/therefore.net\/es\/capabilities\/firmas-electronicas\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/therefore.net\/es\/capabilities\/firmas-electronicas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/therefore.net\/es\/capabilities\/firmas-electronicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/therefore.net\/es\/"},{"@type":"ListItem","position":2,"name":"Firmas electr\u00f3nicas"}]},{"@type":"WebSite","@id":"https:\/\/therefore.net\/es\/#website","url":"https:\/\/therefore.net\/es\/","name":"Therefore","description":"","publisher":{"@id":"https:\/\/therefore.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/therefore.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/therefore.net\/es\/#organization","name":"Therefore","url":"https:\/\/therefore.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/therefore.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2022\/04\/logo.png","contentUrl":"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2022\/04\/logo.png","width":176,"height":48,"caption":"Therefore"},"image":{"@id":"https:\/\/therefore.net\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/therefore-corporation\/","https:\/\/www.youtube.com\/user\/ThereforeTV"]}]}},"_links":{"self":[{"href":"https:\/\/therefore.net\/es\/wp-json\/wp\/v2\/capabilities\/9232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/therefore.net\/es\/wp-json\/wp\/v2\/capabilities"}],"about":[{"href":"https:\/\/therefore.net\/es\/wp-json\/wp\/v2\/types\/capabilities"}],"wp:attachment":[{"href":"https:\/\/therefore.net\/es\/wp-json\/wp\/v2\/media?parent=9232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}