{"id":4515,"date":"2023-03-30T18:57:38","date_gmt":"2023-03-30T16:57:38","guid":{"rendered":"https:\/\/therefore.net\/capabilities\/capture\/"},"modified":"2023-06-04T16:28:45","modified_gmt":"2023-06-04T14:28:45","slug":"capture","status":"publish","type":"capabilities","link":"https:\/\/therefore.net\/fr\/fonctionnalites\/capture\/","title":{"rendered":"Capture"},"content":{"rendered":"<section class=\"custom-block benefits-save-money\">\n    <div class=\"container benefits-save-money__container\">\n        <div class=\"benefits-save-money__inner\">\n\n            <div class=\"benefits-save-money__text-wrapper\">\n                <h2 class=\"benefits-save-money__title\">\n                    \n                <\/h2>\n                                    <div class=\"benefits-save-money__text\"><p>Les avantages de la capture \u00e9lectronique du papier vont au-del\u00e0 de la simple num\u00e9risation des documents papier. En rendant les documents consultables et facilement accessibles sous forme \u00e9lectronique, les entreprises peuvent gagner du temps et am\u00e9liorer leur productivit\u00e9. Les documents peuvent \u00eatre index\u00e9s et organis\u00e9s par date, par type ou par d&#8217;autres m\u00e9tadonn\u00e9es, ce qui permet de trouver plus facilement et rapidement ce dont on a besoin. En outre, la capture \u00e9lectronique du papier permet un stockage plus s\u00fbr des documents, avec la possibilit\u00e9 de d\u00e9finir des contr\u00f4les d&#8217;acc\u00e8s et des autorisations pour les documents sensibles. La capture \u00e9lectronique du papier est particuli\u00e8rement utile pour les secteurs qui g\u00e9n\u00e8rent un volume important de documents papier, tels que les soins de sant\u00e9, les services juridiques et la finance.<\/p>\n<\/div>\n                \n            <\/div>\n\n            <div class=\"benefits-save-money__image-wrapper\">\n                                    <img decoding=\"async\" width=\"1410\" height=\"1060\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture.png\" class=\"attachment-full size-full\" alt=\"La main d&#039;une personne chargeant une pile de papier blanc vierge dans une imprimante ou une photocopieuse, le voyant d&#039;alimentation \u00e9tant allum\u00e9.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture.png 1410w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture-300x226.png 300w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture-1024x770.png 1024w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture-768x577.png 768w\" sizes=\"(max-width: 1410px) 100vw, 1410px\" \/>\n                                            <\/div>\n\n        <\/div>\n    <\/div>\n<\/section>\n<section class=\"custom-block benefits-save-time\">\n    <div class=\"container benefits-save-time__container\">\n        <div class=\"benefits-save-time__inner\">\n            <div class=\"benefits-save-time__left\">\n                <div class=\"benefits-save-time__image-wrapper\">\n                                            <img decoding=\"async\" width=\"1030\" height=\"1120\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture2.png\" class=\"attachment-full size-full\" alt=\"Un homme barbu, v\u00eatu d&#039;une chemise grise, est assis \u00e0 un bureau et tend la main pour placer ou r\u00e9cup\u00e9rer des documents sur une imprimante situ\u00e9e pr\u00e8s d&#039;une fen\u00eatre. La lumi\u00e8re de la fen\u00eatre \u00e9claire l&#039;espace de travail.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture2.png 1030w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture2-276x300.png 276w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture2-942x1024.png 942w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/Capture2-768x835.png 768w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"benefits-save-time__text-wrapper\">\n                <h2 class=\"benefits-save-time__title\">\n                    Therefore\u2122 propose une large s\u00e9lection d&#8217;outils pour vous aider \u00e0 capturer, organiser et g\u00e9rer vos informations.\n                <\/h2>\n                                <ul class=\"benefits-save-time__bullets\">\n                                        <li class=\"benefits-save-time__bullets__item\">Therefore\u2122 Capture Client<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Therefore\u2122 Content Connector<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Therefore\u2122 Document Loader<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Therefore\u2122 Smart Capture<\/li>\n                                        <li class=\"benefits-save-time__bullets__item\">Therefore\u2122 MFP Application<\/li>\n                                    <\/ul>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section class=\"custom-block view-pages-text-paragraph view-pages-text-paragraph--has-image view-pages-text-paragraph--reversed\">\n    <div class=\"container view-pages-text-paragraph__container\">\n        <div class=\"view-pages-text-paragraph__inner\">\n                <div class=\"view-pages-text-paragraph__left\">\n                    <div class=\"view-pages-text-paragraph__image-wrapper\">\n                        \n                            <img decoding=\"async\" width=\"1030\" height=\"1540\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/CaptureClient2.png\" class=\"attachment-full size-full\" alt=\"Capture d&#039;\u00e9cran de la fen\u00eatre d&#039;un logiciel de gestion de documents montrant une liste de fichiers sur la gauche et une partie d&#039;une facture pour &quot;River Springs Marketing&quot; avec ses coordonn\u00e9es sur la droite.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/CaptureClient2.png 1030w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/CaptureClient2-201x300.png 201w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/CaptureClient2-685x1024.png 685w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/CaptureClient2-768x1148.png 768w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/CaptureClient2-1027x1536.png 1027w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/>\n                                            <\/div>\n                <\/div>\n\n            <div class=\"view-pages-text-paragraph__text-wrapper\">\n                                                        <h2 class=\"view-pages-text-paragraph__title\">\n                        Therefore\u2122 Capture Client\n                    <\/h2>\n                \n                                    <div class=\"view-pages-text-paragraph__text\"><p>Les documents papier peuvent \u00eatre num\u00e9ris\u00e9s et reconnus \u00e0 l&#8217;aide du Therefore\u2122 Capture Client. M\u00eame les lots importants de documents peuvent \u00eatre facilement import\u00e9s et index\u00e9s \u00e0 l&#8217;aide de codes-barres ou de la reconnaissance OCR zonale pour capturer automatiquement les donn\u00e9es d&#8217;indexation.<\/p>\n<p>Peut-\u00eatre souhaitez-vous num\u00e9riser vos documents sur un multifonction et utiliser Therefore\u2122 Capture Client pour les indexer et les enregistrer. Aucun probl\u00e8me : il vous suffit d&#8217;enregistrer vos documents num\u00e9ris\u00e9s dans un dossier surveill\u00e9, o\u00f9 ils seront ensuite r\u00e9cup\u00e9r\u00e9s et trait\u00e9s par le Therefore\u2122 Capture Client.<\/p>\n<p>Pour les besoins de num\u00e9risation plus complexes, tels que la reconnaissance automatique des types de documents ou m\u00eame des fournisseurs de factures, nous prenons en charge les int\u00e9grations avec les solutions de num\u00e9risation avanc\u00e9es d&#8217;IRIS. Nous disposons \u00e9galement d&#8217;un connecteur pour Kofax Capture.<\/p>\n<\/div>\n                \n\n                \n\n                                                        <h2 class=\"view-pages-text-paragraph__title view-pages-text-paragraph__title--bottom\">\n                        D\u00e9tendez-vous et laissez Therefore\u2122 s&#8217;occuper du travail de classification de vos documents !\n                    <\/h2>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section class=\"custom-block view-pages-text-paragraph  \">\n    <div class=\"container view-pages-text-paragraph__container\">\n        <div class=\"view-pages-text-paragraph__inner\">\n                <div class=\"view-pages-text-paragraph__left\">\n                    <div class=\"view-pages-text-paragraph__image-wrapper\">\n                                            <\/div>\n                <\/div>\n\n            <div class=\"view-pages-text-paragraph__text-wrapper\">\n                                                        <h2 class=\"view-pages-text-paragraph__title\">\n                        Therefore\u2122 Content Connector\n                    <\/h2>\n                \n                                    <div class=\"view-pages-text-paragraph__text\"><p>Le Therefore\u2122 Content Connector est un outil multifonctionnel qui permet aux utilisateurs de capturer un large \u00e9ventail d&#8217;informations \u00e9lectroniques et de les sauvegarder en toute s\u00e9curit\u00e9 dans l&#8217;archive Therefore\u2122. Les documents cr\u00e9\u00e9s par d&#8217;autres syst\u00e8mes ERP ou CRM peuvent \u00eatre enregistr\u00e9s dans un dossier d&#8217;entr\u00e9e, o\u00f9 ils seront r\u00e9cup\u00e9r\u00e9s et trait\u00e9s par le Content Connector. En outre, la surveillance des bo\u00eetes aux lettres peut enregistrer automatiquement les courriels d&#8217;une certaine bo\u00eete aux lettres dans Therefore\u2122. Ces documents peuvent \u00e9galement \u00eatre configur\u00e9s pour d\u00e9marrer automatiquement un workflow Therefore\u2122 une fois enregistr\u00e9s.<\/p>\n<\/div>\n                \n\n                \n\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"custom-block video-img-section video-img-section--shape \">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/The-Therefore-Content-Connector.mp4\" name=\"therefore-content-connector\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">En savoir plus sur le Therefore\u2122 Content Connector<\/h2>\n                \n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n<section class=\"custom-block view-pages-text-paragraph  view-pages-text-paragraph--reversed\">\n    <div class=\"container view-pages-text-paragraph__container\">\n        <div class=\"view-pages-text-paragraph__inner\">\n                <div class=\"view-pages-text-paragraph__left\">\n                    <div class=\"view-pages-text-paragraph__image-wrapper\">\n                                            <\/div>\n                <\/div>\n\n            <div class=\"view-pages-text-paragraph__text-wrapper\">\n                                                        <h2 class=\"view-pages-text-paragraph__title\">\n                        Therefore\u2122 Document Loader\n                    <\/h2>\n                \n                                    <div class=\"view-pages-text-paragraph__text\"><p>Le Therefore\u2122 Document Loader permet d&#8217;enregistrer rapidement et facilement des lots de documents dans Therefore\u2122. Cet outil simple est inclus dans toutes les versions de Therefore\u2122 et constitue une option populaire pour l&#8217;importation de lots fixes, par opposition aux lots dynamiques, de documents et de leurs m\u00e9tadonn\u00e9es associ\u00e9es. Il est souvent utilis\u00e9 lors de la mise en \u0153uvre, lorsque les documents et les donn\u00e9es sont migr\u00e9s dans le syst\u00e8me Therefore\u2122.<\/p>\n<\/div>\n                \n\n                \n\n                                                        <h2 class=\"view-pages-text-paragraph__title view-pages-text-paragraph__title--bottom\">\n                        Le Document Loader est un outil simple et \u00e9conomique qui permet d&#8217;enregistrer les documents dans Therefore\u2122 !\n                    <\/h2>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<section class=\"custom-block view-pages-text-paragraph view-pages-text-paragraph--has-image \">\n    <div class=\"container view-pages-text-paragraph__container\">\n        <div class=\"view-pages-text-paragraph__inner\">\n                <div class=\"view-pages-text-paragraph__left\">\n                    <div class=\"view-pages-text-paragraph__image-wrapper\">\n                        \n                            <img decoding=\"async\" width=\"1030\" height=\"1540\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/SmartCapture2-e1758285588389.png\" class=\"attachment-full size-full\" alt=\"Illustration abstraite d&#039;un r\u00e9seau neuronal en forme de cerveau, comprenant des n\u0153uds connect\u00e9s et des lignes dans un gradient allant du rouge au violet sur un fond blanc.\" \/>\n                                            <\/div>\n                <\/div>\n\n            <div class=\"view-pages-text-paragraph__text-wrapper\">\n                                                        <h2 class=\"view-pages-text-paragraph__title\">\n                        Therefore\u2122 Smart Capture\n                    <\/h2>\n                \n                                    <div class=\"view-pages-text-paragraph__text\"><p>Therefore\u2122 Smart Capture extrait les donn\u00e9es des factures \u00e0 l&#8217;aide de l&#8217;IA. Il peut traiter rapidement un volume \u00e9lev\u00e9 de factures gr\u00e2ce \u00e0 l&#8217;automatisation. Il stimule la productivit\u00e9 et l&#8217;efficacit\u00e9 des employ\u00e9s tout en diminuant les erreurs caus\u00e9es par le travail manuel. Smart Capture est une approche rentable pour rationaliser le traitement des factures.<\/p>\n<p>Il suffit d&#8217;enregistrer la facture dans une cat\u00e9gorie Therefore\u2122. Le flux de travail s&#8217;occupera du reste, garantissant un processus efficace et rationalis\u00e9. Le flux de travail t\u00e9l\u00e9charge la facture \u00e0 traiter et \u00e0 reconna\u00eetre. Quelques instants plus tard, les utilisateurs peuvent examiner les donn\u00e9es d&#8217;indexation captur\u00e9es pour une validation rapide et facile des donn\u00e9es. Smart Capture \u00e9tant bas\u00e9 sur l&#8217;IA, la validation humaine aide le syst\u00e8me \u00e0 am\u00e9liorer sa pr\u00e9cision et sa capacit\u00e9 \u00e0 comprendre de nouvelles mises en page au fil du temps. Une fois valid\u00e9es, les factures peuvent \u00eatre trait\u00e9es ult\u00e9rieurement \u00e0 l&#8217;aide des flux de travail Therefore\u2122 pour une efficacit\u00e9 accrue.<\/p>\n<\/div>\n                \n\n                \n\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"custom-block video-img-section video-img-section--shape video-img-section--reversed\">\n    <div class=\"container video-img-section__container\">\n\n        <div class=\"video-img-section__row\">\n            <div class=\"video-img-section__media video-img-section__media\">\n                                <div class=\"video-img-section__media__item video-img-section__media__item--video\">\n                                            <video src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/SC-Marketing.mp4\" name=\"sc-marketing\" controls><\/video>\n                                    <\/div>\n                            <\/div>\n\n            <div class=\"video-img-section__content\">\n                                                        <h2 class=\"video-img-section__title\">En savoir plus sur Therefore\u2122 Smart Capture<\/h2>\n                \n                            <\/div>\n        <\/div>\n\n\n    <\/div>\n\n<\/section>\n<section class=\"custom-block view-pages-text-paragraph  \">\n    <div class=\"container view-pages-text-paragraph__container\">\n        <div class=\"view-pages-text-paragraph__inner\">\n                <div class=\"view-pages-text-paragraph__left\">\n                    <div class=\"view-pages-text-paragraph__image-wrapper\">\n                                            <\/div>\n                <\/div>\n\n            <div class=\"view-pages-text-paragraph__text-wrapper\">\n                                                        <h2 class=\"view-pages-text-paragraph__title\">\n                        Therefore\u2122 MFP Application\n                    <\/h2>\n                \n                                    <div class=\"view-pages-text-paragraph__text\"><p>Les sc\u00e9narios de num\u00e9risation plus ad hoc sont bien servis par l&#8217;application Therefore\u2122 MFP App.<\/p>\n<p>Therefore\u2122 MFP Scan permet aux utilisateurs de num\u00e9riser, d&#8217;indexer manuellement, puis d&#8217;enregistrer des documents directement dans Therefore\u2122.<\/p>\n<p>Des fonctionnalit\u00e9s similaires sont \u00e9galement possibles via des connecteurs pour eCopy ShareScan et uniFLOW.<\/p>\n<\/div>\n                \n\n                \n\n                                                        <h2 class=\"view-pages-text-paragraph__title view-pages-text-paragraph__title--bottom\">\n                        L&#8217;application MFP est un excellent compagnon pour votre syst\u00e8me Therefore\u2122 et votre p\u00e9riph\u00e9rique multifonctionnel Canon.\n                    <\/h2>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"custom-block video-img-blue video-img-blue--shape video-img-blue--reversed\">\n    <div class=\"container video-img-blue__container\">\n                \n                    <div class=\"video-img-blue__media video-img-blue__media--image\">\n                                    <div class=\"video-img-blue__media__ratio\">\n                        <img decoding=\"async\" width=\"1280\" height=\"853\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/MFPApplication.jpg\" class=\"attachment-full size-full\" alt=\"La main d&#039;une personne aux ongles manucur\u00e9s touche le panneau de commande tactile d&#039;une imprimante ou d&#039;une photocopieuse de bureau, s\u00e9lectionnant des options sur l&#039;\u00e9cran.\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/MFPApplication.jpg 1280w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/MFPApplication-300x200.jpg 300w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/MFPApplication-1024x682.jpg 1024w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/MFPApplication-768x512.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\n                    <\/div>\n                            <\/div>\n        \n        \n    <\/div>\n<\/section>\n<section class=\"custom-block hero-slider\">\n    <div class=\"hero-slider swiper-container\" data-timer=\"\">\n        <div class=\"swiper-wrapper swiper-wrapper--p-t\">\n                                                        <div class=\"swiper-slide\" data-swiper-autoplay=\"\">\n                    <div class=\"container hero-slider__container\">\n                        <div class=\"hero-slider__slide\">\n                            <div class=\"hero-slider__slide-left\">\n                                <h2 class=\"hero-slider__title\">\n                                    En savoir plus sur le Content Connector\n                                <\/h2>\n                                <p class=\"hero-slider__text text-light\">\n                                    Notre webinaire, &#8220;All About the Content Connector&#8221;, explore la fa\u00e7on dont il peut aider les entreprises de toutes tailles \u00e0 am\u00e9liorer la pr\u00e9cision, la rapidit\u00e9 et l&#8217;efficacit\u00e9 de l&#8217;enregistrement et du traitement des documents.\n                                <\/p>\n                                                                <a class=\"main-button main-button--with-arrow\" target=\"_blank\"\n                                    href=\"https:\/\/www.youtube.com\/watch?v=mr1DC3wMQ9s\">Voir le webinaire (en anglais)<\/a>\n                                                            <\/div>\n                                                            <div class=\"hero-slider__slide-right\">\n                                                                            <img fetchpriority=\"high\" decoding=\"async\" width=\"910\" height=\"684\" src=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/ContentConnectorWebinar.png\" class=\"attachment-1283x684 size-1283x684\" alt=\"Diapositive de webinaire intitul\u00e9e &quot;All about the Content Connector&quot; par Therefore Webinars, comportant une petite photo de Jennifer Schmitt, sp\u00e9cialiste de l&#039;engagement num\u00e9rique, sur un fond blanc avec des graphiques hexagonaux.\" loading=\"eager\" srcset=\"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/ContentConnectorWebinar.png 1410w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/ContentConnectorWebinar-300x226.png 300w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/ContentConnectorWebinar-1024x770.png 1024w, https:\/\/therefore.net\/wp\/..\/app\/uploads\/2023\/03\/ContentConnectorWebinar-768x577.png 768w\" sizes=\"(max-width: 910px) 100vw, 910px\" \/>\n                                                                    <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                                <\/div>\n        <div class=\"swiper-pagination\"><\/div>\n    <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Toutes les organisations traitent plus de donn\u00e9es que jamais. Vous avez besoin d&#8217;une solution pour vous aider \u00e0 capturer et \u00e0 classer l&#8217;avalanche d&#8217;informations dont vous avez besoin pour \u00eatre efficace et efficient.<\/p>\n","protected":false},"template":"","class_list":["post-4515","capabilities","type-capabilities","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Therefore\u2122 Capture<\/title>\n<meta name=\"description\" content=\"Therefore\u2122 offre de nombreuses possibilit\u00e9s pour vous aider \u00e0 capturer, organiser et g\u00e9rer vos informations.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/therefore.net\/fr\/fonctionnalites\/capture\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/fonctionnalites\\\/capture\\\/\",\"url\":\"https:\\\/\\\/therefore.net\\\/fr\\\/fonctionnalites\\\/capture\\\/\",\"name\":\"Therefore\u2122 Capture\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/#website\"},\"datePublished\":\"2023-03-30T16:57:38+00:00\",\"dateModified\":\"2023-06-04T14:28:45+00:00\",\"description\":\"Therefore\u2122 offre de nombreuses possibilit\u00e9s pour vous aider \u00e0 capturer, organiser et g\u00e9rer vos informations.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/fonctionnalites\\\/capture\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/therefore.net\\\/fr\\\/fonctionnalites\\\/capture\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/fonctionnalites\\\/capture\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/therefore.net\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/therefore.net\\\/fr\\\/\",\"name\":\"Therefore\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/therefore.net\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/#organization\",\"name\":\"Therefore\",\"url\":\"https:\\\/\\\/therefore.net\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/therefore.net\\\/wp\\\/..\\\/app\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/therefore.net\\\/wp\\\/..\\\/app\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"width\":176,\"height\":48,\"caption\":\"Therefore\"},\"image\":{\"@id\":\"https:\\\/\\\/therefore.net\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/therefore-corporation\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ThereforeTV\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Therefore\u2122 Capture","description":"Therefore\u2122 offre de nombreuses possibilit\u00e9s pour vous aider \u00e0 capturer, organiser et g\u00e9rer vos informations.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/therefore.net\/fr\/fonctionnalites\/capture\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/therefore.net\/fr\/fonctionnalites\/capture\/","url":"https:\/\/therefore.net\/fr\/fonctionnalites\/capture\/","name":"Therefore\u2122 Capture","isPartOf":{"@id":"https:\/\/therefore.net\/fr\/#website"},"datePublished":"2023-03-30T16:57:38+00:00","dateModified":"2023-06-04T14:28:45+00:00","description":"Therefore\u2122 offre de nombreuses possibilit\u00e9s pour vous aider \u00e0 capturer, organiser et g\u00e9rer vos informations.","breadcrumb":{"@id":"https:\/\/therefore.net\/fr\/fonctionnalites\/capture\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/therefore.net\/fr\/fonctionnalites\/capture\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/therefore.net\/fr\/fonctionnalites\/capture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/therefore.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Capture"}]},{"@type":"WebSite","@id":"https:\/\/therefore.net\/fr\/#website","url":"https:\/\/therefore.net\/fr\/","name":"Therefore","description":"","publisher":{"@id":"https:\/\/therefore.net\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/therefore.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/therefore.net\/fr\/#organization","name":"Therefore","url":"https:\/\/therefore.net\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/therefore.net\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2022\/04\/logo.png","contentUrl":"https:\/\/therefore.net\/wp\/..\/app\/uploads\/2022\/04\/logo.png","width":176,"height":48,"caption":"Therefore"},"image":{"@id":"https:\/\/therefore.net\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/therefore-corporation\/","https:\/\/www.youtube.com\/user\/ThereforeTV"]}]}},"_links":{"self":[{"href":"https:\/\/therefore.net\/fr\/wp-json\/wp\/v2\/capabilities\/4515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/therefore.net\/fr\/wp-json\/wp\/v2\/capabilities"}],"about":[{"href":"https:\/\/therefore.net\/fr\/wp-json\/wp\/v2\/types\/capabilities"}],"wp:attachment":[{"href":"https:\/\/therefore.net\/fr\/wp-json\/wp\/v2\/media?parent=4515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}